{"id":101912,"date":"2024-03-22T03:59:17","date_gmt":"2024-03-22T00:59:17","guid":{"rendered":"https:\/\/emarh.org.sa\/store\/?post_type=product&#038;p=101912"},"modified":"2024-03-22T04:08:47","modified_gmt":"2024-03-22T01:08:47","slug":"%d8%aa%d9%88%d8%b9%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%8a%d8%a9-%d8%a8%d8%a7%d9%84%d9%85%d8%b3%d8%a7%d8%ac%d8%af","status":"publish","type":"product","link":"https:\/\/emarh.org.sa\/store\/product\/%d8%aa%d9%88%d8%b9%d9%8a%d8%a9-%d8%a7%d9%84%d8%b9%d9%86%d8%a7%d9%8a%d8%a9-%d8%a8%d8%a7%d9%84%d9%85%d8%b3%d8%a7%d8%ac%d8%af\/","title":{"rendered":"\u062a\u0648\u0639\u064a\u0629 \u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0645\u0633\u0627\u062c\u062f"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u0628\u0631\u0646\u0627\u0645\u062c \u064a\u0647\u062f\u0641 \u0625\u0644\u0649 \u0627\u0644\u062a\u0648\u0639\u064a\u0629 \u0639\u0646 \u0627\u0644\u0639\u0646\u0627\u064a\u0629 \u0628\u0627\u0644\u0645\u0633\u0627\u062c\u062f\u060c \u0648\u0631\u0641\u0639 \u0646\u0633\u0628\u0629 \u0648\u0639\u064a \u0627\u0644\u0645\u062c\u062a\u0645\u0639 &#8230; <\/p>\n","protected":false},"featured_media":101904,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[96],"product_tag":[],"class_list":{"0":"post-101912","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-alms-and-zakat","8":"first","9":"instock","10":"featured","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/emarh.org.sa\/store\/wp-json\/wp\/v2\/product\/101912","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/emarh.org.sa\/store\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/emarh.org.sa\/store\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/emarh.org.sa\/store\/wp-json\/wp\/v2\/comments?post=101912"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/emarh.org.sa\/store\/wp-json\/wp\/v2\/media\/101904"}],"wp:attachment":[{"href":"https:\/\/emarh.org.sa\/store\/wp-json\/wp\/v2\/media?parent=101912"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/emarh.org.sa\/store\/wp-json\/wp\/v2\/product_brand?post=101912"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/emarh.org.sa\/store\/wp-json\/wp\/v2\/product_cat?post=101912"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/emarh.org.sa\/store\/wp-json\/wp\/v2\/product_tag?post=101912"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}